{"id":2893,"date":"2016-11-14T20:32:25","date_gmt":"2016-11-14T20:32:25","guid":{"rendered":"http:\/\/www.majory-cubizolles.fr\/blog\/?p=2893"},"modified":"2017-01-23T18:22:06","modified_gmt":"2017-01-23T18:22:06","slug":"supprimez-champs-objet-formulaire-de-contact-prestashop-1-6","status":"publish","type":"post","link":"https:\/\/www.majory-cubizolles.fr\/blog\/supprimez-champs-objet-formulaire-de-contact-prestashop-1-6\/","title":{"rendered":"Supprimez le champs \u00ab\u00a0objet\u00a0\u00bb du formulaire de contact | Prestashop 1.6"},"content":{"rendered":"<p>Il est tr\u00e8s important d&rsquo;avoir un formulaire de contact simple, efficace et ergonomique.<\/p>\n<p>Pour un premier contact, le formulaire que propose Prestashop est tr\u00e8s bien. Le seul champs que je supprimerais est \u00a0le champs \u00ab\u00a0Objet\u00a0\u00bb. Il vous facilite peut-\u00eatre la t\u00e2che mais il complique celle de votre client.<\/p>\n<p>Si le client oublie de faire sa s\u00e9lection\u00a0(par d\u00e9faut Service client ou\u00a0Webmaster), Prestashop va g\u00e9n\u00e9rer une erreur.<\/p>\n<p><a href=\"http:\/\/www.majory-cubizolles.fr\/blog\/supprimez-champs-objet-formulaire-de-contact-prestashop-1-6\/etape-1-objet-contact-client\/\" rel=\"attachment wp-att-2894\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-2894\" src=\"http:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/11\/Etape-1-objet-contact-client.jpg\" alt=\"Supprimez le champs &quot;objet&quot; du formulaire de contact | Prestashop 1.6\" width=\"800\" height=\"441\" srcset=\"https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/11\/Etape-1-objet-contact-client.jpg 800w, https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/11\/Etape-1-objet-contact-client-300x165.jpg 300w, https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/11\/Etape-1-objet-contact-client-624x344.jpg 624w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><!--more--><\/p>\n<p>Voici un petit tutoriel qui vous permettre de supprimer ce champs.<\/p>\n<p><span style=\"color: #003366;\"><strong>Etape 1:<\/strong> <\/span>Ouvrir le fichier \u00ab\u00a0contact-form.tpl\u00a0\u00bb situ\u00e9 dans th\u00e8mes\/nomdemontheme\/<\/p>\n<p>Mettre les lignes suivantes en commentaire (\u00e0 partir de la ligne 58)<\/p>\n<pre class=\"lang:default decode:true \">&lt;div class=\"form-group selector1\"&gt;\r\n &lt;label for=\"id_contact\"&gt;{l s='Subject Heading'}&lt;\/label&gt;\r\n   {if isset($customerThread.id_contact) &amp;&amp; $customerThread.id_contact &amp;&amp; $contacts|count}\r\n      {assign var=flag value=true}\r\n      {foreach from=$contacts item=contact}\r\n      {if $contact.id_contact == $customerThread.id_contact}\r\n\t&lt;input type=\"text\" class=\"form-control\" id=\"contact_name\" name=\"contact_name\" value=\"{$contact.name|escape:'html':'UTF-8'}\" readonly=\"readonly\" \/&gt;\r\n\t&lt;input type=\"hidden\" name=\"id_contact\" value=\"{$contact.id_contact|intval}\" \/&gt;\r\n      {$flag=false}\r\n     {\/if}\r\n     {\/foreach}\r\n     {if $flag &amp;&amp; isset($contacts.0.id_contact)}\r\n        &lt;input type=\"text\" class=\"form-control\" id=\"contact_name\" name=\"contact_name\" value=\"{$contacts.0.name|escape:'html':'UTF-8'}\" readonly=\"readonly\" \/&gt;\r\n\t&lt;input type=\"hidden\" name=\"id_contact\" value=\"{$contacts.0.id_contact|intval}\" \/&gt;\r\n      {\/if}\r\n      &lt;\/div&gt;\r\n      {else}\r\n\t&lt;select id=\"id_contact\" class=\"form-control\" name=\"id_contact\"&gt;\r\n\t  &lt;option value=\"0\"&gt;{l s='-- Choose --'}&lt;\/option&gt;\r\n\t  {foreach from=$contacts item=contact}\r\n\t    &lt;option value=\"{$contact.id_contact|intval}\"{if isset($smarty.request.id_contact) &amp;&amp; $smarty.request.id_contact == $contact.id_contact} selected=\"selected\"{\/if}&gt;{$contact.name|escape:'html':'UTF-8'}&lt;\/option&gt;\r\n\t  {\/foreach}\r\n\t&lt;\/select&gt;\r\n\t&lt;\/div&gt;\r\n\t&lt;p id=\"desc_contact0\" class=\"desc_contact{if isset($smarty.request.id_contact)} unvisible{\/if}\"&gt;&amp;nbsp;&lt;\/p&gt;\r\n\t  {foreach from=$contacts item=contact}\r\n\t    &lt;p id=\"desc_contact{$contact.id_contact|intval}\" class=\"desc_contact contact-title{if !isset($smarty.request.id_contact) || $smarty.request.id_contact|intval != $contact.id_contact|intval} unvisible{\/if}\"&gt;\r\n\t     &lt;i class=\"icon-comment-alt\"&gt;&lt;\/i&gt;{$contact.description|escape:'html':'UTF-8'}\r\n\t    &lt;\/p&gt;\r\n\t  {\/foreach}\r\n  {\/if}<\/pre>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366;\"><strong>Etape 2:<\/strong> <\/span>Ins\u00e9rez juste en dessous le code suivant:<\/p>\n<pre class=\"lang:default decode:true\">&lt;input type=\"hidden\" name=\"id_contact\" value=\"{$contacts.0.id_contact|intval}\" \/&gt;<\/pre>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366;\"><strong>Etape 3:<\/strong><\/span> Nettoyer votre cache<\/p>\n<p>A) Allez dans l&rsquo;onglet Param\u00e8tres Avanc\u00e9s &gt; Performances<\/p>\n<p><a href=\"http:\/\/www.majory-cubizolles.fr\/blog\/supprimez-champs-objet-formulaire-de-contact-prestashop-1-6\/etape-1-nettoyer-cache\/\" rel=\"attachment wp-att-2895\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-2895\" src=\"http:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/11\/Etape-1-nettoyer-cache.jpg\" alt=\"Nettoyer le cache de Prestashop\" width=\"522\" height=\"637\" srcset=\"https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/11\/Etape-1-nettoyer-cache.jpg 522w, https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/11\/Etape-1-nettoyer-cache-246x300.jpg 246w\" sizes=\"(max-width: 522px) 100vw, 522px\" \/><\/a><\/p>\n<p>B) En haut \u00e0 droite cliquez sur \u00ab\u00a0Videz le Cache\u00a0\u00bb<\/p>\n<p><a href=\"http:\/\/www.majory-cubizolles.fr\/blog\/supprimez-champs-objet-formulaire-de-contact-prestashop-1-6\/etape-2-nettoyer-cache\/\" rel=\"attachment wp-att-2896\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-2896\" src=\"http:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/11\/Etape-2-nettoyer-cache.jpg\" alt=\"Nettoyer le cache de Prestashop\" width=\"800\" height=\"309\" srcset=\"https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/11\/Etape-2-nettoyer-cache.jpg 800w, https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/11\/Etape-2-nettoyer-cache-300x116.jpg 300w, https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/11\/Etape-2-nettoyer-cache-624x241.jpg 624w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>C&rsquo;est tout. Le champs \u00ab\u00a0objet\u00a0\u00bb de votre formulaire de contact a disparu.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<ul>\n<li>Astuce donn\u00e9e par\u00a0<code class=\"php plain\">Webbax<\/code><\/li>\n<\/ul>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-2'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Articles similaires<\/h2><\/div>\n\t\t\t\t\t\t<div class=\"relatedthumb yuzo-list  \" style=\"\"  >  \n\t\t\t\t\t\t  <a  href=\"https:\/\/www.majory-cubizolles.fr\/blog\/les-fonctionnalites-de-prestashop-pour-vos-clients\/\" class=\"image-list\" target='_blank' >\n\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 185px;height:150px;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t <div class=\"yuzo-img\" style=\"background:url('https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2021\/01\/fonctionnalites-client-prestashop-400x249.jpg') 50% 50% no-repeat;width: 190px;height:150px;margin-bottom: 5px;background-size:  cover;  \"><\/div>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <\/a>\n\t\t\t\t\t\t  <a  class=\"link-list yuzo__text--title\" href=\"https:\/\/www.majory-cubizolles.fr\/blog\/les-fonctionnalites-de-prestashop-pour-vos-clients\/\" style=\"font-size:15px;font-weight:bold;;line-height:23px;\"> Les fonctionnalit\u00e9s de PrestaShop pour vos clients  <div class='yuzo_views_post yuzo_icon_views yuzo_icon_views__bottom' style='font-size:13px;'>views 292<\/div><\/a>\n\t\t\t\t\t\t\t\t<span class=\"yuzo_text\" style=\"font-size:11px;\" >Nativement PrestaShop propose une large palette de fonctionnalit\u00e9s qui permet \u00e0 vos clients d'avoir une exp\u00e9rience d'achat optimis\u00e9e, une pr\u00e9sentation compl\u00e8te de vos produits.\r\nVoici une liste de ces fonctionnalit\u00e9s:\r\n\r\nEXPERIENCE D\u2019ACHAT OPTIMISE\r\n\u2014 Navigation \u00e0 facettes (filtre les produits par caract\u00e9ristiques)\r\n\u2014 Outils de recherche int\u00e9gr\u00e9s puissants\r\n\u2014 Bas de page enrichi avec liens d'acc\u00e8s...<\/span>\n\t\t\t\t\t\t   \n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"relatedthumb yuzo-list  \" style=\"\"  >  \n\t\t\t\t\t\t  <a  href=\"https:\/\/www.majory-cubizolles.fr\/blog\/augmenter-taille-de-description-courte-prestashop\/\" class=\"image-list\" target='_blank' >\n\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 185px;height:150px;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t <div class=\"yuzo-img\" style=\"background:url('https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/07\/descriptioncourte-400x249.jpg') 50% 50% no-repeat;width: 190px;height:150px;margin-bottom: 5px;background-size:  cover;  \"><\/div>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <\/a>\n\t\t\t\t\t\t  <a  class=\"link-list yuzo__text--title\" href=\"https:\/\/www.majory-cubizolles.fr\/blog\/augmenter-taille-de-description-courte-prestashop\/\" style=\"font-size:15px;font-weight:bold;;line-height:23px;\"> Comment augmenter la taille de la description courte dans Prestashop  <div class='yuzo_views_post yuzo_icon_views yuzo_icon_views__bottom' style='font-size:13px;'>views 4182<\/div><\/a>\n\t\t\t\t\t\t\t\t<span class=\"yuzo_text\" style=\"font-size:11px;\" >Lors de la cr\u00e9ation de la fiche produit sur Prestashop, vous serez\u00a0peut-\u00eatre \u00eatre bloqu\u00e9 par la limitation du nombre de caract\u00e8res de la description courte (maximum 400 caract\u00e8res)\r\n\r\n\r\n\r\n\r\n\r\nBonne nouvelle, pas besoin d'aller dans le code, une simple manipulation \u00e0 faire dans le back-office de Prestashop\r\nComment modifie t-on le nombre de caract\u00e8re ?\u00a0\r\nA) Connectez-vous dans le back-office de Pre...<\/span>\n\t\t\t\t\t\t   \n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"relatedthumb yuzo-list  \" style=\"\"  >  \n\t\t\t\t\t\t  <a  href=\"https:\/\/www.majory-cubizolles.fr\/blog\/greffer-le-module-bloc-social-dans-displaynav\/\" class=\"image-list\" target='_blank' >\n\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 185px;height:150px;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t <div class=\"yuzo-img\" style=\"background:url('https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/07\/wsi-imageoptim-Capture-d\u2019\u00e9cran-2015-04-24-\u00e0-21.46.32-400x249.jpg') 50% 50% no-repeat;width: 190px;height:150px;margin-bottom: 5px;background-size:  cover;  \"><\/div>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <\/a>\n\t\t\t\t\t\t  <a  class=\"link-list yuzo__text--title\" href=\"https:\/\/www.majory-cubizolles.fr\/blog\/greffer-le-module-bloc-social-dans-displaynav\/\" style=\"font-size:15px;font-weight:bold;;line-height:23px;\"> Greffer le module bloc social dans displayNav |  Astuce Prestashop 1.6  <div class='yuzo_views_post yuzo_icon_views yuzo_icon_views__bottom' style='font-size:13px;'>views 2897<\/div><\/a>\n\t\t\t\t\t\t\t\t<span class=\"yuzo_text\" style=\"font-size:11px;\" >Ce tutoriel va vous permettre de greffer le module \"bloc social\" dans displayNav\r\n\r\nCette astuce Prestashop est valable pour la version 1.6\r\n\r\n--------------------------------------------------------\r\n\r\nOn va dans un premier temps\u00a0modifier le fichier\u00a0blocksocial.php\r\n\r\n1) Pour cela allez dans modules > blocksocial> blocksocial.php. Tout \u00e0\u00a0la fin du code, juste avant la derni\u00e8re accolade coll...<\/span>\n\t\t\t\t\t\t   \n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"relatedthumb yuzo-list  \" style=\"\"  >  \n\t\t\t\t\t\t  <a  href=\"https:\/\/www.majory-cubizolles.fr\/blog\/ajouter-les-fabricants-dans-la-page-produit-astuce-prestashop\/\" class=\"image-list\" target='_blank' >\n\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 185px;height:150px;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t <div class=\"yuzo-img\" style=\"background:url('https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/07\/wsi-imageoptim-ecommerce-2-400x249.jpg') 50% 50% no-repeat;width: 190px;height:150px;margin-bottom: 5px;background-size:  cover;  \"><\/div>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <\/a>\n\t\t\t\t\t\t  <a  class=\"link-list yuzo__text--title\" href=\"https:\/\/www.majory-cubizolles.fr\/blog\/ajouter-les-fabricants-dans-la-page-produit-astuce-prestashop\/\" style=\"font-size:15px;font-weight:bold;;line-height:23px;\"> Ajouter les fabricants dans la page produit |  Astuce Prestashop 1.6  <div class='yuzo_views_post yuzo_icon_views yuzo_icon_views__bottom' style='font-size:13px;'>views 2803<\/div><\/a>\n\t\t\t\t\t\t\t\t<span class=\"yuzo_text\" style=\"font-size:11px;\" >Ce tuto va vous expliquer comment ins\u00e9rer les fabricants dans la page\u00a0produit dans la version Prestashop 1.6\r\n\r\nA) Mettre le nom du fabricant avec le lien sur la page produit\u00a0\r\nAjouter les lignes suivantes dans le fichier product.tpl\u00a0qui se situe dans votre th\u00e8me \u00e0 l'endroit \u00e0 vous d\u00e9sirez que le fabricant apparaisse :\u00a0\r\n\r\nR\u00e9sultat :\u00a0\r\n\r\n\r\n\r\nB) Mettre le logo du fabricant avec le lien sur la page ...<\/span>\n\t\t\t\t\t\t   \n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"relatedthumb yuzo-list  \" style=\"\"  >  \n\t\t\t\t\t\t  <a  href=\"https:\/\/www.majory-cubizolles.fr\/blog\/la-difference-entre-pinterest-et-instagram-infographie\/\" class=\"image-list\" target='_blank' >\n\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 185px;height:150px;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t <div class=\"yuzo-img\" style=\"background:url('https:\/\/www.majory-cubizolles.fr\/blog\/wp-content\/uploads\/2016\/07\/wsi-imageoptim-Capture-d\u2019\u00e9cran-2015-06-01-\u00e0-21.52.25-400x249.jpg') 50% 50% no-repeat;width: 190px;height:150px;margin-bottom: 5px;background-size:  cover;  \"><\/div>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <\/a>\n\t\t\t\t\t\t  <a  class=\"link-list yuzo__text--title\" href=\"https:\/\/www.majory-cubizolles.fr\/blog\/la-difference-entre-pinterest-et-instagram-infographie\/\" style=\"font-size:15px;font-weight:bold;;line-height:23px;\"> La diff\u00e9rence entre Pinterest et Instagram | Infographie  <div class='yuzo_views_post yuzo_icon_views yuzo_icon_views__bottom' style='font-size:13px;'>views 504<\/div><\/a>\n\t\t\t\t\t\t\t\t<span class=\"yuzo_text\" style=\"font-size:11px;\" >Cette infographie va vous permettre de connaitre les diff\u00e9rences entre les deux r\u00e9seaux sociaux : Pinterest & Instagram\r\nPinterest\u00a0permet de cr\u00e9er des tableaux o\u00f9 vous pouvez accrocher gr\u00e2ce \u00e0 des \"punaises\", des \u201cpin\u201d, tout ce que vous aimez, en particulier des photos ou des images. \u00c0 l\u2019instar de Facebook, vous pouvez \u00e9changer, partager, aimer ce que vous appr\u00e9ciez et ce que vos amis appr\u00e9cie...<\/span>\n\t\t\t\t\t\t   \n\t\t\t\t\t\t<\/div>\n<\/div>  <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Il est tr\u00e8s important d&rsquo;avoir un formulaire de contact simple, efficace et ergonomique. Pour un premier contact, le formulaire que propose Prestashop est tr\u00e8s bien. Le seul champs que je supprimerais est \u00a0le champs \u00ab\u00a0Objet\u00a0\u00bb. Il vous facilite peut-\u00eatre la t\u00e2che mais il complique celle de votre client. Si le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,11],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.majory-cubizolles.fr\/blog\/wp-json\/wp\/v2\/posts\/2893"}],"collection":[{"href":"https:\/\/www.majory-cubizolles.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.majory-cubizolles.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.majory-cubizolles.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.majory-cubizolles.fr\/blog\/wp-json\/wp\/v2\/comments?post=2893"}],"version-history":[{"count":0,"href":"https:\/\/www.majory-cubizolles.fr\/blog\/wp-json\/wp\/v2\/posts\/2893\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.majory-cubizolles.fr\/blog\/wp-json\/wp\/v2\/media\/2899"}],"wp:attachment":[{"href":"https:\/\/www.majory-cubizolles.fr\/blog\/wp-json\/wp\/v2\/media?parent=2893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.majory-cubizolles.fr\/blog\/wp-json\/wp\/v2\/categories?post=2893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.majory-cubizolles.fr\/blog\/wp-json\/wp\/v2\/tags?post=2893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}